{"id":42940,"date":"2025-01-29T12:58:51","date_gmt":"2025-01-29T17:58:51","guid":{"rendered":"http:\/\/www.web2025.virgiliogalvis.com\/?post_type=services&#038;p=42940"},"modified":"2025-03-11T12:41:04","modified_gmt":"2025-03-11T17:41:04","slug":"camara-retiniana-trc-50-dx","status":"publish","type":"services","link":"https:\/\/virgiliogalvis.com\/en\/services\/camara-retiniana-trc-50-dx\/","title":{"rendered":"Angiography"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"42940\" class=\"elementor elementor-42940\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef253af e-flex e-con-boxed cmsmasters-block-default e-con e-parent\" data-id=\"ef253af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6452261 e-con-full e-flex cmsmasters-block-default e-con e-child\" data-id=\"6452261\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68bbd31 cmsmasters-block-default cmsmasters-sticky-default elementor-widget elementor-widget-image\" data-id=\"68bbd31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"http:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1-30x30.jpg\" class=\"attachment-medium size-medium wp-image-42947 cmsmasters_img cmsmasters-lazyload lazyload\" alt=\"\" data-sizes=\"(max-width: 300px) 100vw, 300px\" data-src=\"http:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1-300x300.jpg\" data-srcset=\"http:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1-300x300.jpg 300w, http:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1-150x150.jpg 150w, http:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1-260x260.jpg 260w, http:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1-30x30.jpg 30w, http:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1-10x10.jpg 10w, http:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1.jpg 500w\" srcset=\"https:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1-30x30.jpg 30w, https:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1-300x300.jpg 300w, https:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1-150x150.jpg 150w, https:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1-260x260.jpg 260w, https:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1-10x10.jpg 10w, https:\/\/virgiliogalvis.com\/wp-content\/uploads\/2025\/01\/HISCAN-OPTICON1.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83223d1 cmsmasters-block-default cmsmasters-sticky-default elementor-widget elementor-widget-heading\" data-id=\"83223d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">C\u00c1MARA RETINIANA TRC 50 DX\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a5211a cmsmasters-block-default cmsmasters-sticky-default elementor-widget elementor-widget-text-editor\" data-id=\"3a5211a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"iw-heading style1 border-left\"><div class=\"iwh-sub-title\"><div class=\"iw-heading  style1  border-left\"><div class=\"iwh-sub-title\">Marca: TOPCON<\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec41f4a cmsmasters-tabs-type-vertical cmsmasters-list-item-alignment-left cmsmasters-icon-position-left cmsmasters-tabs-position-start cmsmasters-tabs-responsive-mobile cmsmasters-type-responsive-accordion cmsmasters-accordion-icon-position-right cmsmasters-accordion-icon-view-default cmsmasters-icon-view-default cmsmasters-pointer-none cmsmasters-block-default cmsmasters-sticky-default elementor-widget elementor-widget-cmsmasters-tabs cmsmasters-widget-tabs\" data-id=\"ec41f4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;tabs&quot;:[{&quot;tab_title&quot;:&quot;Examen&quot;,&quot;tab_content&quot;:&quot;&lt;ul&gt;&lt;li class=\\&quot;p1\\&quot;&gt;&lt;span class=\\&quot;s1\\&quot;&gt;Ecograf\\u00eda&lt;\\\/span&gt;&lt;\\\/li&gt;&lt;li class=\\&quot;p1\\&quot;&gt;&lt;span class=\\&quot;s1\\&quot;&gt;Biomicroscop\\u00eda Ultras\\u00f3nica&lt;\\\/span&gt;&lt;\\\/li&gt;&lt;\\\/ul&gt;&quot;,&quot;_id&quot;:&quot;0409198&quot;,&quot;content_type&quot;:&quot;tab-content&quot;,&quot;saved_section&quot;:null,&quot;tab_subtitle&quot;:&quot;&quot;,&quot;tab_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;tab_custom_id&quot;:&quot;&quot;},{&quot;tab_title&quot;:&quot;\\u00bfQu\\u00e9 hace?&quot;,&quot;tab_content&quot;:&quot;&lt;p class=\\&quot;p1\\&quot;&gt;&lt;span class=\\&quot;s1\\&quot;&gt;Es una t\\u00e9cnica de diagn\\u00f3stico por imagen que estudia las estructuras del globo ocular y las estructuras anexas a la \\u00f3rbita (m\\u00fasculos, gl\\u00e1ndula lagrimal, grasa orbitaria, etc.) mediante ultrasonidos. Al igual que las ecograf\\u00edas abdominales o de otras partes del cuerpo, para realizar una ecograf\\u00eda ocular se extiende un gel sobre la piel del paciente (en este caso el p\\u00e1rpado, aunque se puede realizar directamente sobre el globo ocular) y se pone en contacto la sonda del ec\\u00f3grafo con dicho gel para obtener las im\\u00e1genes.&lt;\\\/span&gt;&lt;\\\/p&gt;&lt;p class=\\&quot;p1\\&quot;&gt;&lt;span class=\\&quot;s1\\&quot;&gt;La Biomicroscop\\u00eda Ultras\\u00f3nica (UBM) es una t\\u00e9cnica ecogr\\u00e1fica de alta resoluci\\u00f3n que permite analizar con detalle las estructuras del segmento anterior ocular, estructuras de otro modo ocultas pues no se pueden apreciar por otros medios o equipamientos. Aunque es un m\\u00e9todo lento en su realizaci\\u00f3n comparado con otras t\\u00e9cnicas de estudio del polo anterior, permite el an\\u00e1lisis detallado de la c\\u00e1mara posterior ocular. Se considera una t\\u00e9cnica muy \\u00fatil en la implantaci\\u00f3n de lentes intraoculares f\\u00e1quicas y es imprescindible en el estudio de ciertos tumores del segmento anterior ocular. Otras utilidades importantes son los casos de glaucoma y su seguimiento postoperatorio. Es una t\\u00e9cnica \\u00fatil, as\\u00ed mismo, en pacientes que presenten opacidad de medios y por ello se vea dificultada la exploraci\\u00f3n del segmento anterior ocular por otros medios.&lt;\\\/span&gt;&lt;\\\/p&gt;&quot;,&quot;_id&quot;:&quot;f2cb1bb&quot;,&quot;content_type&quot;:&quot;tab-content&quot;,&quot;saved_section&quot;:null,&quot;tab_subtitle&quot;:&quot;&quot;,&quot;tab_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;tab_custom_id&quot;:&quot;&quot;},{&quot;_id&quot;:&quot;25862ec&quot;,&quot;tab_content&quot;:&quot;&lt;p&gt;La aberrometr\\u00eda nos permite realizar el an\\u00e1lisis de las propiedades \\u00f3pticas de la c\\u00f3rnea a partir de su morfolog\\u00eda. El estudio de las aberraciones corneales tiene m\\u00faltiples usos en oftalmolog\\u00eda: entre otros, el estudio de la calidad \\u00f3ptica de la c\\u00f3rnea normal y patol\\u00f3gica, la elecci\\u00f3n de lentes intraoculares en funci\\u00f3n de la aberraci\\u00f3n esf\\u00e9rica corneal y la aplicaci\\u00f3n de tratamientos personalizados con l\\u00e1ser\\u00a0excimer\\u00a0guiados por aberrometr\\u00eda corneal. El mapa aberrom\\u00e9trico puede utilizarse para dise\\u00f1ar un mapa de ablaci\\u00f3n personalizado para su utilizaci\\u00f3n en una plataforma de l\\u00e1ser\\u00a0excimer\\u00a0con la finalidad de corregir las aberraciones de alto orden que presenta el paciente y mejorar la calidad visual tras la cirug\\u00eda refractiva corneal.&lt;\\\/p&gt;&quot;,&quot;tab_title&quot;:&quot;\\u00bfPara qu\\u00e9 sirve?&quot;,&quot;content_type&quot;:&quot;tab-content&quot;,&quot;saved_section&quot;:null,&quot;tab_subtitle&quot;:&quot;&quot;,&quot;tab_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;tab_custom_id&quot;:&quot;&quot;}],&quot;tabs_type&quot;:&quot;vertical&quot;,&quot;default_tab&quot;:1,&quot;tabs_responsive&quot;:&quot;mobile&quot;,&quot;tabs_responsive_type&quot;:&quot;accordion&quot;,&quot;tabs_responsive_choose&quot;:&quot;accordion&quot;}\" data-widget_type=\"cmsmasters-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"cmsmasters-tabs\" role=\"tablist\"><div class=\"cmsmasters-tabs-list-wrapper\">\n\t\t\t<ul class=\"cmsmasters-tabs-list\"><li id=\"cmsmasters-tabs-list-item_2471\" class=\"cmsmasters-tabs-list-item cmsmasters-animation\" data-tab=\"1\"><a href=\"\" class=\"cmsmasters-tab-title\">\n\t\t\t\t\t\t\t<div class=\"cmsmasters-tab-title__text-wrap-outer\"><div class=\"cmsmasters-tab-title__text-wrap\"><h6 class=\"cmsmasters-tab-title__text \">Examen<\/h6><\/div><\/div><\/a><\/li><li id=\"cmsmasters-tabs-list-item_2472\" class=\"cmsmasters-tabs-list-item cmsmasters-animation\" data-tab=\"2\"><a href=\"\" class=\"cmsmasters-tab-title\">\n\t\t\t\t\t\t\t<div class=\"cmsmasters-tab-title__text-wrap-outer\"><div class=\"cmsmasters-tab-title__text-wrap\"><h6 class=\"cmsmasters-tab-title__text \">\u00bfQu\u00e9 hace?<\/h6><\/div><\/div><\/a><\/li><li id=\"cmsmasters-tabs-list-item_2473\" class=\"cmsmasters-tabs-list-item cmsmasters-animation\" data-tab=\"3\"><a href=\"\" class=\"cmsmasters-tab-title\">\n\t\t\t\t\t\t\t<div class=\"cmsmasters-tab-title__text-wrap-outer\"><div class=\"cmsmasters-tab-title__text-wrap\"><h6 class=\"cmsmasters-tab-title__text \">\u00bfPara qu\u00e9 sirve?<\/h6><\/div><\/div><\/a><\/li><\/ul>\n\t\t<\/div><div class=\"cmsmasters-tabs-wrap\"><div class=\"cmsmasters-accordion-item-wrap\"><div id=\"cmsmasters-accordion-item-2471\" class=\"cmsmasters-tabs-list-item cmsmasters-accordion-item cmsmasters-animation\" data-tab=\"1\"><a href=\"\" class=\"cmsmasters-tab-title\"><span class=\"cmsmasters-tab-icon cmsmasters-accordion-closed fas fa-plus icon-align-right\"><\/span><span class=\"cmsmasters-tab-icon cmsmasters-accordion-opened fas fa-minus icon-align-right\"><\/span><div class=\"cmsmasters-tab-title__text-wrap-outer\"><div class=\"cmsmasters-tab-title__text-wrap\"><div class=\"cmsmasters-tab-title__text \">Examen<\/div><\/div><\/div><\/a><\/div><div id=\"cmsmasters-tab-content_2471\" class=\"cmsmasters-tab\" data-tab=\"1\"><ul><li class=\"p1\"><span class=\"s1\">Ecograf\u00eda<\/span><\/li><li class=\"p1\"><span class=\"s1\">Biomicroscop\u00eda Ultras\u00f3nica<\/span><\/li><\/ul><\/div><\/div><div class=\"cmsmasters-accordion-item-wrap\"><div id=\"cmsmasters-accordion-item-2472\" class=\"cmsmasters-tabs-list-item cmsmasters-accordion-item cmsmasters-animation\" data-tab=\"2\"><a href=\"\" class=\"cmsmasters-tab-title\"><span class=\"cmsmasters-tab-icon cmsmasters-accordion-closed fas fa-plus icon-align-right\"><\/span><span class=\"cmsmasters-tab-icon cmsmasters-accordion-opened fas fa-minus icon-align-right\"><\/span><div class=\"cmsmasters-tab-title__text-wrap-outer\"><div class=\"cmsmasters-tab-title__text-wrap\"><div class=\"cmsmasters-tab-title__text \">\u00bfQu\u00e9 hace?<\/div><\/div><\/div><\/a><\/div><div id=\"cmsmasters-tab-content_2472\" class=\"cmsmasters-tab\" data-tab=\"2\"><p class=\"p1\"><span class=\"s1\">Es una t\u00e9cnica de diagn\u00f3stico por imagen que estudia las estructuras del globo ocular y las estructuras anexas a la \u00f3rbita (m\u00fasculos, gl\u00e1ndula lagrimal, grasa orbitaria, etc.) mediante ultrasonidos. Al igual que las ecograf\u00edas abdominales o de otras partes del cuerpo, para realizar una ecograf\u00eda ocular se extiende un gel sobre la piel del paciente (en este caso el p\u00e1rpado, aunque se puede realizar directamente sobre el globo ocular) y se pone en contacto la sonda del ec\u00f3grafo con dicho gel para obtener las im\u00e1genes.<\/span><\/p><p class=\"p1\"><span class=\"s1\">La Biomicroscop\u00eda Ultras\u00f3nica (UBM) es una t\u00e9cnica ecogr\u00e1fica de alta resoluci\u00f3n que permite analizar con detalle las estructuras del segmento anterior ocular, estructuras de otro modo ocultas pues no se pueden apreciar por otros medios o equipamientos. Aunque es un m\u00e9todo lento en su realizaci\u00f3n comparado con otras t\u00e9cnicas de estudio del polo anterior, permite el an\u00e1lisis detallado de la c\u00e1mara posterior ocular. Se considera una t\u00e9cnica muy \u00fatil en la implantaci\u00f3n de lentes intraoculares f\u00e1quicas y es imprescindible en el estudio de ciertos tumores del segmento anterior ocular. Otras utilidades importantes son los casos de glaucoma y su seguimiento postoperatorio. Es una t\u00e9cnica \u00fatil, as\u00ed mismo, en pacientes que presenten opacidad de medios y por ello se vea dificultada la exploraci\u00f3n del segmento anterior ocular por otros medios.<\/span><\/p><\/div><\/div><div class=\"cmsmasters-accordion-item-wrap\"><div id=\"cmsmasters-accordion-item-2473\" class=\"cmsmasters-tabs-list-item cmsmasters-accordion-item cmsmasters-animation\" data-tab=\"3\"><a href=\"\" class=\"cmsmasters-tab-title\"><span class=\"cmsmasters-tab-icon cmsmasters-accordion-closed fas fa-plus icon-align-right\"><\/span><span class=\"cmsmasters-tab-icon cmsmasters-accordion-opened fas fa-minus icon-align-right\"><\/span><div class=\"cmsmasters-tab-title__text-wrap-outer\"><div class=\"cmsmasters-tab-title__text-wrap\"><div class=\"cmsmasters-tab-title__text \">\u00bfPara qu\u00e9 sirve?<\/div><\/div><\/div><\/a><\/div><div id=\"cmsmasters-tab-content_2473\" class=\"cmsmasters-tab\" data-tab=\"3\"><p>La aberrometr\u00eda nos permite realizar el an\u00e1lisis de las propiedades \u00f3pticas de la c\u00f3rnea a partir de su morfolog\u00eda. El estudio de las aberraciones corneales tiene m\u00faltiples usos en oftalmolog\u00eda: entre otros, el estudio de la calidad \u00f3ptica de la c\u00f3rnea normal y patol\u00f3gica, la elecci\u00f3n de lentes intraoculares en funci\u00f3n de la aberraci\u00f3n esf\u00e9rica corneal y la aplicaci\u00f3n de tratamientos personalizados con l\u00e1ser\u00a0excimer\u00a0guiados por aberrometr\u00eda corneal. El mapa aberrom\u00e9trico puede utilizarse para dise\u00f1ar un mapa de ablaci\u00f3n personalizado para su utilizaci\u00f3n en una plataforma de l\u00e1ser\u00a0excimer\u00a0con la finalidad de corregir las aberraciones de alto orden que presenta el paciente y mejorar la calidad visual tras la cirug\u00eda refractiva corneal.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Retinal Camera CRT 50 DX Brand: TOPCON Examination What does it do? What is it for? Ultrasonic Biomicroscopy Examination What does it do? It is an imaging diagnostic technique that studies the structures of the eyeball and the structures surrounding the orbit (muscles, lacrimal gland, orbital fat, etc.) using ultrasound. Similar to abdominal ultrasounds or\u2026<\/p>","protected":false},"featured_media":43849,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"class_list":["post-42940","services","type-services","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/virgiliogalvis.com\/en\/wp-json\/wp\/v2\/services\/42940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/virgiliogalvis.com\/en\/wp-json\/wp\/v2\/services"}],"about":[{"href":"https:\/\/virgiliogalvis.com\/en\/wp-json\/wp\/v2\/types\/services"}],"version-history":[{"count":8,"href":"https:\/\/virgiliogalvis.com\/en\/wp-json\/wp\/v2\/services\/42940\/revisions"}],"predecessor-version":[{"id":42951,"href":"https:\/\/virgiliogalvis.com\/en\/wp-json\/wp\/v2\/services\/42940\/revisions\/42951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/virgiliogalvis.com\/en\/wp-json\/wp\/v2\/media\/43849"}],"wp:attachment":[{"href":"https:\/\/virgiliogalvis.com\/en\/wp-json\/wp\/v2\/media?parent=42940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}